{"id":61711,"date":"2023-12-13T10:23:21","date_gmt":"2023-12-13T10:23:21","guid":{"rendered":"https:\/\/equibel.be\/politique-de-confidentialite\/"},"modified":"2026-05-07T08:28:57","modified_gmt":"2026-05-07T08:28:57","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"61711\" class=\"elementor elementor-61711 elementor-43654\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e46166 e-flex e-con-boxed e-con e-parent\" data-id=\"8e46166\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1af85b5 e-flex e-con-boxed e-con e-child\" data-id=\"1af85b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61b9dbe elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"61b9dbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/equibel.be\/fr\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Politique de confidentialit\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1e8399 elementor-widget elementor-widget-heading\" data-id=\"b1e8399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-120b4b9 e-flex e-con-boxed e-con e-parent\" data-id=\"120b4b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b71bd14 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"b71bd14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Conditions d&rsquo;utilisation<\/strong><\/h2>\n<h4><strong>1. Dispositions g\u00e9n\u00e9rales<\/strong><\/h4>\nLa Plateforme d&rsquo;information de la F\u00e9d\u00e9ration des sports \u00e9questres offre divers services op\u00e9rationnels \u00e0 ses membres pour l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres, y compris des comp\u00e9titions, des entra\u00eenements et d&rsquo;autres activit\u00e9s pertinentes. Via la Plateforme, les organisateurs d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres peuvent planifier et mettre en place des \u00e9v\u00e9nements, ouvrir des \u00e9v\u00e9nements \u00e0 l&rsquo;inscription, traiter les paiements, les versements et les remboursements, pr\u00e9parer les inscriptions et les donn\u00e9es d&rsquo;inscription pour organiser un concours, ainsi que documenter, saisir et publier les r\u00e9sultats. Ci-apr\u00e8s, le terme \u00ab organisateur \u00bb d\u00e9signe le r\u00f4le de l&rsquo;instance administrative, du club h\u00f4te et du b\u00e9n\u00e9ficiaire financier. Ces r\u00f4les peuvent \u00eatre remplis par une ou plusieurs personnes morales en collaboration entre elles et avec la FRBSE-KBRSF. Via la Plateforme, la FRBSE-KBRSF facilite les inscriptions des athl\u00e8tes aux \u00e9v\u00e9nements sous l&rsquo;autorit\u00e9 de la F\u00e9d\u00e9ration \u00c9questre Internationale (FEI) et d&rsquo;autres autorit\u00e9s internationales des sports \u00e9questres des disciplines soutenues (par exemple la FITE), approuve ou refuse les inscriptions, \u00e9change des donn\u00e9es avec la FEI et d&rsquo;autres autorit\u00e9s internationales des sports \u00e9questres, re\u00e7oit les r\u00e9sultats de la base de donn\u00e9es de la FEI et d&rsquo;autres sources utilis\u00e9es pour calculer les qualifications, les classements, les handicaps et publier des statistiques. Les donn\u00e9es de r\u00e9sultats et les donn\u00e9es personnelles telles que l&rsquo;\u00e2ge, l&rsquo;affiliation ou l&rsquo;adh\u00e9sion \u00e0 un club d\u00e9termin\u00e9 ou \u00e0 une organisation r\u00e9gionale sont trait\u00e9es afin de valider si les athl\u00e8tes, les chevaux et les combinaisons sont \u00e9ligibles \u00e0 la participation aux \u00e9v\u00e9nements de sports \u00e9questres. Les donn\u00e9es de r\u00e9sultats sont \u00e9galement trait\u00e9es pour calculer les qualifications, les classements, les handicaps et d&rsquo;autres r\u00e9sultats analytiques, publier des statistiques et \u00e9tablir et publier des rapports. La FRBSE-KBRSF facilite l&rsquo;immatriculation des chevaux dans la base de donn\u00e9es, traite les immatriculations de chevaux, les enregistrements aupr\u00e8s de la FEI, les d\u00e9clarations concernant le changement de personnes responsables et d&rsquo;organisations de chevaux, la documentation relative aux mesures de poneys, le passeport FEI, les cartes d&rsquo;identification, les duplicatas et les autocollants ainsi que les paiements pour ces demandes et services. La FRBSE-KBRSF est habilit\u00e9e \u00e0 ajouter des donn\u00e9es de chevaux \u00e0 la base de donn\u00e9es de la FEI et \u00e0 activer les enregistrements annuels FEI pour les chevaux et les athl\u00e8tes participant \u00e0 des \u00e9v\u00e9nements internationaux. La FRBSE-KBRSF collecte et traite les donn\u00e9es relatives aux organisateurs (organisations affili\u00e9es, telles que les autorit\u00e9s r\u00e9gionales) d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres, y compris la gestion des autorisations et de l&rsquo;acc\u00e8s des organisateurs \u00e0 leurs propres donn\u00e9es et \u00e0 celles des participants, tel que configur\u00e9 sur la base des r\u00e8glements de la FRBSE-KBRSF. La FRBSE-KBRSF et les organisations affili\u00e9es (ligues) traitent les licences des athl\u00e8tes, y compris la collecte et le traitement des informations n\u00e9cessaires aux d\u00e9cisions relatives aux licences, telles que les dipl\u00f4mes de sports \u00e9questres, les certificats et l&rsquo;exp\u00e9rience ant\u00e9rieure dans les sports \u00e9questres. La FRBSE-KBRSF g\u00e8re le processus d&rsquo;attribution et de renouvellement des qualifications professionnelles des officiels hippiques et des entra\u00eeneurs dans les sports \u00e9questres, ainsi que du personnel administratif des organisations affili\u00e9es.         \n\nLa Plateforme d&rsquo;information de la F\u00e9d\u00e9ration des sports \u00e9questres (FIPA) est conc\u00e9d\u00e9e sous licence \u00e0 la FRBSE-KBRSF (ci-apr\u00e8s d\u00e9nomm\u00e9e \u00ab prestataire de services \u00bb). Le domaine de FIPA est https:\/\/competitions.equibel.be. FIPA est destin\u00e9e \u00e0 l&rsquo;organisation de concours \u00e9questres dans toutes les disciplines de la FEI (F\u00e9d\u00e9ration \u00c9questre Internationale) ainsi qu&rsquo;en Western Riding, Pony Games, Horseball et TREC, et aide aux t\u00e2ches de gestion dans les sports \u00e9questres. Les configurations de FIPA suivent le cadre r\u00e9glementaire belge pour les sports \u00e9questres. FIPA traite les informations relatives aux utilisateurs finaux impliqu\u00e9s dans les sports \u00e9questres (athl\u00e8tes, repr\u00e9sentants d&rsquo;organisations, personnes responsables de chevaux, officiels des sports \u00e9questres, personnel administratif, etc.). Elle assure \u00e9galement les op\u00e9rations techniques, y compris l&rsquo;\u00e9change de donn\u00e9es avec d&rsquo;autres services, et fournit des analyses bas\u00e9es sur les donn\u00e9es op\u00e9rationnelles collect\u00e9es, y compris les r\u00e9sultats de comp\u00e9titions, les qualifications, les classements, les handicaps, les statistiques et les rapports. L&rsquo;utilisation du syst\u00e8me par les utilisateurs finaux est approuv\u00e9e par la FRBSE-KBRSF et doit se faire conform\u00e9ment \u00e0 la l\u00e9gislation nationale et aux r\u00e8glements de la FRBSE-KBRSF. Les utilisateurs de moins de 18 ans ne peuvent utiliser le syst\u00e8me qu&rsquo;avec le consentement de leurs parents et\/ou tuteurs l\u00e9gaux et ne sont pas autoris\u00e9s \u00e0 utiliser des cartes de cr\u00e9dit pour payer les services et produits via FIPA. Les pr\u00e9sentes conditions d&rsquo;utilisation s&rsquo;appliquent \u00e9galement aux parents ou tuteurs l\u00e9gaux des utilisateurs de moins de 18 ans. Le responsable du traitement des donn\u00e9es est la FRBSE-KBRSF. Le sous-traitant des donn\u00e9es est Fipatech O\u00dc, tous les droits sur le contenu de FIPA appartiennent \u00e0 Fipatech O\u00dc.      \n<h4>\n<strong>2. Modifications des services et des configurations<\/strong><\/h4>\nLe prestataire de services et\/ou le sous-traitant peuvent \u00e0 tout moment et sans pr\u00e9avis apporter des modifications aux configurations et aux fonctions ou fonctionnalit\u00e9s de la FIPA. Avant d&rsquo;apporter des modifications, nous examinons l&rsquo;impact de celles-ci sur nos utilisateurs finaux et, si cet impact est important et n\u00e9gatif, nous informons raisonnablement nos utilisateurs des modifications. La documentation et les instructions diffus\u00e9es via le Help Desk sont mises \u00e0 jour en cons\u00e9quence. Les utilisateurs acceptent les modifications lorsqu&rsquo;ils utilisent le service.   \n<h4><strong>3. Compte et inscription<\/strong><\/h4>\nTous les utilisateurs du syst\u00e8me Equidata re\u00e7oivent un compte dans FIPA. De nouveaux comptes d&rsquo;utilisateurs sont ajout\u00e9s \u00e0 la demande d&rsquo;un utilisateur ou via les registres de membres des associations de sports \u00e9questres Bridle et Equiclub. Les informations relatives au registre des membres (Bridle et Equiclub) sont synchronis\u00e9es directement et en continu. Les titulaires d&rsquo;un compte peuvent se connecter \u00e0 FIPA avec leur adresse e-mail et\/ou leur num\u00e9ro de licence et cr\u00e9er un mot de passe. Un compte pour les responsables de chevaux sera cr\u00e9\u00e9 ou mis \u00e0 jour apr\u00e8s confirmation de la demande d&rsquo;immatriculation du cheval ou de la demande de modification des donn\u00e9es du responsable du cheval. Les comptes pour le personnel administratif, les cavaliers \u00e9trangers et\/ou les officiels sont cr\u00e9\u00e9s sur demande. Si n\u00e9cessaire, le consentement de la personne concern\u00e9e sera obtenu. Tous les clubs hippiques et organisations r\u00e9gionales affili\u00e9s \u00e0 la FRBSE-KBRSF re\u00e7oivent un profil dans FIPA. Les administrateurs du profil sont d\u00e9sign\u00e9s par la FRBSE-KBRSF (membres du personnel). Les collaborateurs peuvent \u00eatre g\u00e9r\u00e9s par d&rsquo;autres collaborateurs et par la FRBSE-KBRSF. L&rsquo;ouverture d&rsquo;un compte pour une personne physique ou d&rsquo;un profil pour une personne morale est gratuite. Le prestataire de services se r\u00e9serve le droit de refuser l&rsquo;ouverture d&rsquo;un compte ou la cr\u00e9ation d&rsquo;un profil. Le prestataire de services peut refuser l&rsquo;utilisation des services s&rsquo;il le juge n\u00e9cessaire, y compris la suspension ou la r\u00e9siliation de l&rsquo;acc\u00e8s au compte ou \u00e0 certaines fonctionnalit\u00e9s, c&rsquo;est-\u00e0-dire les inscriptions aux \u00e9v\u00e9nements sous le compte.        \n<h4><strong>4. Informations personnelles et leur utilisation<\/strong><\/h4>\nLes donn\u00e9es personnelles de l&rsquo;utilisateur sont transf\u00e9r\u00e9es depuis le syst\u00e8me Equidata, Bridle ou Equiclub ou sont collect\u00e9es aupr\u00e8s des utilisateurs. Les donn\u00e9es de base requises sont le nom, l&rsquo;adresse, l&rsquo;e-mail, le num\u00e9ro de t\u00e9l\u00e9phone, la date de naissance, le sexe, le num\u00e9ro d&rsquo;identification national, le nom d&rsquo;utilisateur (num\u00e9ro de licence) et le mot de passe. Le syst\u00e8me collecte et stocke des informations suppl\u00e9mentaires, telles que le num\u00e9ro de licence FEI, les donn\u00e9es relatives \u00e0 l&rsquo;affiliation au club, les donn\u00e9es relatives aux licences et aux paiements des licences, les donn\u00e9es relatives aux qualifications professionnelles et \u00e0 l&rsquo;exp\u00e9rience professionnelle, les examens, les dipl\u00f4mes et certificats, l&rsquo;adresse IP et d&rsquo;autres informations. Le prestataire de services ne divulgue pas d&rsquo;informations personnelles \u00e0 des tiers, sauf lorsque la divulgation est requise par la loi et\/ou par la r\u00e9glementation impos\u00e9e par le prestataire de services en mati\u00e8re de sports \u00e9questres. L&rsquo;utilisateur a le droit de v\u00e9rifier les donn\u00e9es personnelles collect\u00e9es dans le syst\u00e8me. Pour plus d&rsquo;informations sur la protection des donn\u00e9es, veuillez consulter la D\u00e9claration de confidentialit\u00e9.    \n<h4><strong>5. Responsabilit\u00e9s des utilisateurs<\/strong><\/h4>\nNous attendons des utilisateurs qu&rsquo;ils maintiennent un environnement respectueux lorsqu&rsquo;ils utilisent nos services et qu&rsquo;ils prennent toutes les mesures raisonnables pour prot\u00e9ger leur compte et leurs donn\u00e9es personnelles. Il est interdit de divulguer le nom d&rsquo;utilisateur et le mot de passe \u00e0 des tiers. L&rsquo;utilisateur doit informer imm\u00e9diatement le prestataire de services si le nom d&rsquo;utilisateur et le mot de passe ont \u00e9t\u00e9 divulgu\u00e9s \u00e0 des tiers. Lors de l&rsquo;utilisation de nos services au nom d&rsquo;une organisation, c&rsquo;est-\u00e0-dire pour l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres, un repr\u00e9sentant autoris\u00e9 de l&rsquo;organisation doit accepter les pr\u00e9sentes conditions d&rsquo;utilisation et les appliquer dans l&rsquo;ex\u00e9cution de son travail. Ci-apr\u00e8s, le terme \u00ab organisateur \u00bb d\u00e9signe tous les r\u00f4les associ\u00e9s aux \u00e9v\u00e9nements de sports \u00e9questres, y compris une autorit\u00e9 administrative, un club h\u00f4te et un b\u00e9n\u00e9ficiaire financier. Ces r\u00f4les peuvent \u00eatre remplis conform\u00e9ment aux proc\u00e9dures internes et aux r\u00e8glements par une ou plusieurs personnes morales en collaboration entre elles et avec la FRBSE-KBRSF. Le prestataire de services n&rsquo;est pas responsable des dommages suivants : perte de b\u00e9n\u00e9fices, de revenus, d&rsquo;opportunit\u00e9s commerciales, de goodwill ou d&rsquo;\u00e9conomies escompt\u00e9es, dommages indirects ou cons\u00e9cutifs, dommages punitifs. Les services ne peuvent \u00eatre utilis\u00e9s que pour les finalit\u00e9s pour lesquelles ils ont \u00e9t\u00e9 con\u00e7us et de mani\u00e8re appropri\u00e9e. Si un utilisateur final ou une organisation partage ou diffuse du contenu via les services (logos, documents, photos, etc.), il incombe \u00e0 l&rsquo;utilisateur ou \u00e0 l&rsquo;utilisateur agissant au nom d&rsquo;une organisation de s&rsquo;assurer qu&rsquo;il\/elle dispose de tous les droits n\u00e9cessaires pour ce faire et que le contenu est licite. Dans le syst\u00e8me, les utilisateurs ont acc\u00e8s \u00e0 la propri\u00e9t\u00e9 intellectuelle d&rsquo;autres utilisateurs (logos, photos, descriptions d&rsquo;\u00e9v\u00e9nements \u00e9questres, documents relatifs \u00e0 des \u00e9v\u00e9nements \u00e9questres, etc.). Les utilisateurs ne sont pas autoris\u00e9s \u00e0 utiliser ce contenu sans l&rsquo;autorisation du propri\u00e9taire, ou sauf disposition contraire de la loi.       \n<h4>\n<strong>6. Licences et assurances des athl\u00e8tes<\/strong><\/h4>\nLes licences sont un service payant du LEWB et de Paardensport Vlaanderen \u00e0 leurs membres. L&rsquo;obtention d&rsquo;une premi\u00e8re licence ou le renouvellement d&rsquo;une licence ne peut se faire qu&rsquo;avec le consentement de l&rsquo;utilisateur. Il est interdit d&rsquo;agir au nom d&rsquo;un utilisateur sans son consentement. Le prestataire de services v\u00e9rifie les crit\u00e8res d&rsquo;admissibilit\u00e9 pour l&rsquo;achat ou la mise \u00e0 niveau d&rsquo;une licence avant de permettre \u00e0 un utilisateur de commander et de payer le service de licence. Les crit\u00e8res d&rsquo;admissibilit\u00e9 peuvent inclure : l&rsquo;\u00e2ge, le niveau de licence ant\u00e9rieur, le statut de membre d&rsquo;un club, le statut de membre du conseil d&rsquo;administration ou de fonctionnaire sportif, les dipl\u00f4mes et certificats, la nationalit\u00e9 et d&rsquo;autres param\u00e8tres pertinents. Des r\u00e9ductions peuvent s&rsquo;appliquer en fonction des caract\u00e9ristiques individuelles de l&rsquo;utilisateur. Les licences achet\u00e9es ne sont g\u00e9n\u00e9ralement pas rembours\u00e9es. Cependant, une demande peut \u00eatre introduite aupr\u00e8s de la ligue concern\u00e9e, expliquant les circonstances et les raisons d&rsquo;un \u00e9ventuel remboursement. La ligue \u00e9value la demande et prend une d\u00e9cision concernant un \u00e9ventuel remboursement et la r\u00e9duction du niveau de licence. Lorsque les utilisateurs paient pour des services d&rsquo;assurance, ils concluent un accord contractuel avec le fournisseur de services d&rsquo;assurance des ligues respectives. Les conditions d&rsquo;utilisation des assurances peuvent \u00eatre consult\u00e9es aupr\u00e8s des ligues, en fonction du choix de l&rsquo;utilisateur.        \n<h4><strong>7. Inscriptions et engagements aux \u00e9v\u00e9nements \u00e9questres<\/strong><\/h4>\nLes inscriptions et les engagements pour la participation \u00e0 des \u00e9v\u00e9nements hippiques via le syst\u00e8me doivent se faire conform\u00e9ment aux prescriptions du prestataire de services et conform\u00e9ment aux instructions de l&rsquo;organisateur de l&rsquo;\u00e9v\u00e9nement. L&rsquo;utilisateur peut autoriser l&rsquo;organisateur de l&rsquo;\u00e9v\u00e9nement ou un autre utilisateur \u00e0 l&rsquo;inscrire \u00e0 un \u00e9v\u00e9nement. Il est interdit de faire participer d&rsquo;autres personnes \u00e0 des \u00e9v\u00e9nements sans leur consentement. L&rsquo;inscription n&rsquo;est valable que si elle est compl\u00e8te et contient toutes les informations requises. Si l&rsquo;organisateur utilise les services de paiement du syst\u00e8me, l&rsquo;inscription est valable lorsqu&rsquo;elle est int\u00e9gralement pr\u00e9pay\u00e9e. L&rsquo;inscription doit \u00eatre pay\u00e9e avant la fin de la p\u00e9riode pendant laquelle l&rsquo;\u00e9v\u00e9nement est ouvert aux inscriptions en ligne. Si le nombre maximum d&rsquo;inscriptions pour une comp\u00e9tition, un groupe de comp\u00e9titions, une journ\u00e9e de comp\u00e9tition, l&rsquo;ensemble de l&rsquo;\u00e9v\u00e9nement ou toute autre limite est atteint, aucune inscription suppl\u00e9mentaire ne sera accept\u00e9e et les inscriptions non pay\u00e9es ne pourront \u00eatre pay\u00e9es ni confirm\u00e9es. Si une participation n&rsquo;est pas pay\u00e9e, elle est automatiquement annul\u00e9e. L&rsquo;utilisateur n&rsquo;a aucun droit de r\u00e9tablir la participation annul\u00e9e. Les inscriptions apr\u00e8s la date limite d&rsquo;inscription ne peuvent \u00eatre accept\u00e9es que par l&rsquo;interm\u00e9diaire de l&rsquo;organisateur de l&rsquo;\u00e9v\u00e9nement et un suppl\u00e9ment aux frais d&rsquo;inscription peut s&rsquo;appliquer. Si l&rsquo;inscription est effectu\u00e9e hors ligne sous la forme d&rsquo;une demande orale ou \u00e9crite \u00e0 l&rsquo;organisateur, des frais d&rsquo;inscription hors ligne peuvent s&rsquo;appliquer. Les remboursements pour les inscriptions annul\u00e9es sont g\u00e9n\u00e9ralement vers\u00e9s dans les 5 jours ouvrables suivant la fin de l&rsquo;\u00e9v\u00e9nement, sauf si le prestataire de paiement pr\u00e9voit des dispositions diff\u00e9rentes pour le mode de paiement concern\u00e9. Le paiement des remboursements via le syst\u00e8me rel\u00e8ve de la responsabilit\u00e9 de l&rsquo;organisateur de l&rsquo;\u00e9v\u00e9nement. Les inscriptions aux \u00e9v\u00e9nements internationaux (FEI) sont soumises \u00e0 des frais administratifs. Les frais administratifs sont regroup\u00e9s et factur\u00e9s au d\u00e9but du mois pour les \u00e9v\u00e9nements internationaux dont les r\u00e9sultats du mois pr\u00e9c\u00e9dent ont \u00e9t\u00e9 publi\u00e9s. En s&rsquo;inscrivant \u00e0 un \u00e9v\u00e9nement hippique international ou en autorisant le personnel du prestataire de services \u00e0 effectuer ou \u00e0 modifier des inscriptions, l&rsquo;utilisateur accepte l&rsquo;obligation de paiement des frais administratifs. Les factures relatives aux frais administratifs sont \u00e9mises via FIPA et rendues accessibles dans le panier de l&rsquo;utilisateur responsable. Le prestataire de services accepte les paiements en ligne pour les factures. Si la facture est pay\u00e9e en dehors de FIPA, l&rsquo;utilisateur doit contacter le prestataire de services et fournir une preuve de paiement. Le d\u00e9lai de paiement de ces factures est de 21 jours et doit \u00eatre respect\u00e9.                 \n<h4><strong>8. Services relatifs aux chevaux<\/strong><\/h4>\nPour l&rsquo;immatriculation d&rsquo;un cheval, l&rsquo;introduction d&rsquo;une demande de modification des donn\u00e9es d&rsquo;un responsable et d&rsquo;autres demandes, des frais administratifs peuvent \u00eatre demand\u00e9s par la FRBSE-KBRSF. Le service est fourni (cheval immatricul\u00e9, personnes responsables modifi\u00e9es) apr\u00e8s r\u00e9ception d&rsquo;une preuve de paiement. Dans certains cas, le prestataire de services peut imposer des proc\u00e9dures suppl\u00e9mentaires, par exemple un contr\u00f4le manuel et une v\u00e9rification de l&rsquo;exactitude des donn\u00e9es, notamment par des recoupements de donn\u00e9es dans des bases de donn\u00e9es ouvertes ou par la comparaison des donn\u00e9es avec des scans fournis de documents officiels. Si les donn\u00e9es fournies par l&rsquo;utilisateur sont inexactes, le prestataire de services peut refuser l&rsquo;immatriculation d&rsquo;un cheval et\/ou corriger les donn\u00e9es du cheval sans demander le consentement de l&rsquo;utilisateur. Lors de l&rsquo;utilisation des services via FIPA, la facture est \u00e9tablie apr\u00e8s confirmation du paiement et r\u00e9ception de la preuve de paiement. Les frais administratifs pay\u00e9s ne sont pas rembours\u00e9s.    \n<h4><strong>9. Paiements<\/strong><\/h4>\nLors de l&rsquo;utilisation du syst\u00e8me de paiement, l&rsquo;utilisateur peut payer par carte de d\u00e9bit ou de cr\u00e9dit ou par tout autre moyen de paiement disponible dans le syst\u00e8me. Le prestataire de paiement du service de paiement en ligne est Stripe Payments : www.stripe.com. En acceptant les pr\u00e9sentes conditions, l&rsquo;utilisateur accepte \u00e9galement les conditions d&rsquo;utilisation de Stripe : Consumer Terms of Service (stripe.com) et la d\u00e9claration de confidentialit\u00e9 (Stripe Privacy Policy : https:\/\/stripe.com\/en-no\/privacy). Les utilisateurs de moins de 18 ans ne sont pas autoris\u00e9s \u00e0 payer par carte de cr\u00e9dit. Aucune information de carte n&rsquo;est stock\u00e9e dans FIPA. Le prestataire de services ou le sous-traitant des donn\u00e9es peut contacter les services d&rsquo;assistance de STRIPE au nom des utilisateurs, lorsque ceux-ci y ont consenti, afin de v\u00e9rifier le statut des paiements ou des remboursements et\/ou d&rsquo;informer STRIPE de d\u00e9fauts et de probl\u00e8mes susceptibles d&rsquo;\u00eatre am\u00e9lior\u00e9s.   \n<h4><strong>10. Communications relatives aux services<\/strong><\/h4>\nLes notifications, rappels, confirmations et annonces sont envoy\u00e9s par le syst\u00e8me et\/ou notre Helpdesk afin de faciliter l&rsquo;utilisation des services. Les communications peuvent \u00e9galement \u00eatre adress\u00e9es aux tuteurs l\u00e9gaux de mineurs et, dans certaines circonstances, au personnel agissant au nom d&rsquo;organisations. En r\u00e8gle g\u00e9n\u00e9rale, les communications sont adress\u00e9es \u00e0 l&rsquo;adresse e-mail principale de l&rsquo;utilisateur et \u00e0 l&rsquo;adresse e-mail du tuteur, si celle-ci a \u00e9t\u00e9 fournie. L&rsquo;utilisateur doit s&rsquo;assurer que les communications peuvent \u00eatre livr\u00e9es dans sa bo\u00eete de r\u00e9ception et que l&rsquo;adresse e-mail est correctement orthographi\u00e9e. Le prestataire de services n&rsquo;est pas responsable de tout dommage caus\u00e9 par des communications non livr\u00e9es ou non lues, y compris les dommages suivants : perte de b\u00e9n\u00e9fices, de revenus, d&rsquo;opportunit\u00e9s commerciales, de goodwill ou d&rsquo;\u00e9conomies escompt\u00e9es, dommages indirects ou cons\u00e9cutifs, dommages punitifs. Sur la base des retours des utilisateurs, tels que des suggestions pour am\u00e9liorer les services, nous pouvons donner suite aux retours des utilisateurs sans obligation envers les utilisateurs.\n<br\/>    \n<h4><strong>11. Enregistrement annuel FEI<\/strong><\/h4>\nLa plateforme FIPA facilite l&rsquo;\u00e9mission des enregistrements annuels FEI pour les chevaux.\nSi vous avez demand\u00e9 un enregistrement annuel pour le Concours Complet, la FEI suppose que vous avez accept\u00e9 les conditions l\u00e9gales suivantes :\n\u00ab Dans le cadre de ses efforts pour am\u00e9liorer la gestion des risques en Concours Complet, la FEI a ajout\u00e9 une divulgation obligatoire d&rsquo;informations m\u00e9dicales\/v\u00e9t\u00e9rinaires \u00e0 la proc\u00e9dure d&rsquo;enregistrement pour le Concours Complet. Cette divulgation permet \u00e0 la FEI de collecter et d&rsquo;\u00e9valuer des donn\u00e9es m\u00e9dicales\/v\u00e9t\u00e9rinaires relatives aux informations sur les blessures et les traitements vous concernant en tant qu&rsquo;athl\u00e8te et\/ou concernant votre cheval. Cela est fait pour soutenir l&rsquo;analyse du type exact de blessures subies en Concours Complet, de la valeur des \u00e9quipements de protection et de la qualit\u00e9 et de la nature des services m\u00e9dicaux et v\u00e9t\u00e9rinaires. Toutes ces informations sont trait\u00e9es de mani\u00e8re strictement confidentielle et utilis\u00e9es principalement pour produire des statistiques cumulatives qui nous aideront \u00e0 am\u00e9liorer continuellement la gestion des risques du sport. Nous vous remercions de votre aide dans cet effort. \u00bb\n<h4><strong>12. Droit applicable et juridiction<\/strong><\/h4>\nLes pr\u00e9sentes conditions d&rsquo;utilisation et tout litige ou r\u00e9clamation d\u00e9coulant de ou en lien avec ces conditions d&rsquo;utilisation ou leur objet ou leur formation sont r\u00e9gis et interpr\u00e9t\u00e9s conform\u00e9ment au droit belge. Les tribunaux de Bruxelles sont exclusivement comp\u00e9tents pour trancher tout litige ou r\u00e9clamation d\u00e9coulant de ou en lien avec les pr\u00e9sentes conditions d&rsquo;utilisation. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home Politique de confidentialit\u00e9 Politique de confidentialit\u00e9 Conditions d&rsquo;utilisation 1. Dispositions g\u00e9n\u00e9rales La Plateforme d&rsquo;information de la F\u00e9d\u00e9ration des sports \u00e9questres offre divers services op\u00e9rationnels \u00e0 ses membres pour l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres, y compris des comp\u00e9titions, des entra\u00eenements et d&rsquo;autres activit\u00e9s pertinentes. Via la Plateforme, les organisateurs d&rsquo;\u00e9v\u00e9nements de sports \u00e9questres peuvent planifier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49845,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-61711","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - FRBSE - KBRSF<\/title>\n<meta name=\"description\" content=\"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - FRBSE - KBRSF\" \/>\n<meta property=\"og:description\" content=\"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"FRBSE - KBRSF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/equibel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T08:28:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Featuredkbrsf.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - FRBSE - KBRSF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equibel.be\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Featuredkbrsf.webp\",\"datePublished\":\"2023-12-13T10:23:21+00:00\",\"dateModified\":\"2026-05-07T08:28:57+00:00\",\"description\":\"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equibel.be\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Featuredkbrsf.webp\",\"contentUrl\":\"https:\\\/\\\/equibel.be\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Featuredkbrsf.webp\",\"width\":400,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equibel.be\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/equibel.be\\\/fr\\\/\",\"name\":\"FRBSE - KBRSF\",\"description\":\"Belgian Equistrian Federation\",\"publisher\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equibel.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#organization\",\"name\":\"FRBSE - KBRSF\",\"url\":\"https:\\\/\\\/equibel.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/equibel.be\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo-KBRSF.webp\",\"contentUrl\":\"https:\\\/\\\/equibel.be\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo-KBRSF.webp\",\"width\":334,\"height\":110,\"caption\":\"FRBSE - KBRSF\"},\"image\":{\"@id\":\"https:\\\/\\\/equibel.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/equibel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - FRBSE - KBRSF","description":"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - FRBSE - KBRSF","og_description":"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.","og_url":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/","og_site_name":"FRBSE - KBRSF","article_publisher":"https:\/\/www.facebook.com\/equibel","article_modified_time":"2026-05-07T08:28:57+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Featuredkbrsf.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/","url":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - FRBSE - KBRSF","isPartOf":{"@id":"https:\/\/equibel.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/#primaryimage"},"image":{"@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/#primaryimage"},"thumbnailUrl":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Featuredkbrsf.webp","datePublished":"2023-12-13T10:23:21+00:00","dateModified":"2026-05-07T08:28:57+00:00","description":"Explorez nos disciplines, suivez notre calendrier ou consultez les derniers r\u00e9sultats. Chez Equibel, vous trouverez tout ce dont vous avez besoin dans le monde des sports \u00e9questres.","breadcrumb":{"@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equibel.be\/fr\/politique-de-confidentialite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/#primaryimage","url":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Featuredkbrsf.webp","contentUrl":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Featuredkbrsf.webp","width":400,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/equibel.be\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equibel.be\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/equibel.be\/fr\/#website","url":"https:\/\/equibel.be\/fr\/","name":"FRBSE - KBRSF","description":"Belgian Equistrian Federation","publisher":{"@id":"https:\/\/equibel.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equibel.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/equibel.be\/fr\/#organization","name":"FRBSE - KBRSF","url":"https:\/\/equibel.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/equibel.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Logo-KBRSF.webp","contentUrl":"https:\/\/equibel.be\/wp-content\/uploads\/2023\/11\/Logo-KBRSF.webp","width":334,"height":110,"caption":"FRBSE - KBRSF"},"image":{"@id":"https:\/\/equibel.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/equibel"]}]}},"_links":{"self":[{"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/pages\/61711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/comments?post=61711"}],"version-history":[{"count":2,"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/pages\/61711\/revisions"}],"predecessor-version":[{"id":61737,"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/pages\/61711\/revisions\/61737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/media\/49845"}],"wp:attachment":[{"href":"https:\/\/equibel.be\/fr\/wp-json\/wp\/v2\/media?parent=61711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}